{"id":1652,"date":"2023-02-01T15:02:22","date_gmt":"2023-02-01T14:02:22","guid":{"rendered":"https:\/\/fit-up.com\/?p=1652"},"modified":"2024-10-17T13:26:47","modified_gmt":"2024-10-17T11:26:47","slug":"so-wird-man-schlechte-gewohnheiten-los","status":"publish","type":"post","link":"https:\/\/fit-up.com\/en\/so-wird-man-schlechte-gewohnheiten-los\/","title":{"rendered":"So wird man schlechte Gewohnheiten los?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Manche schlechten Gewohnheiten m\u00f6chten wir am liebsten so schnell wie m\u00f6glich loswerden. Doch warum ist das oft so schwierig? Wieso h\u00e4ngt unser Gehirn so sehr an wiederkehrenden Verhaltensweisen und was k\u00f6nnen wir dagegen tun?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es ist eine Zahl, die selbst Psychologen aufhorchen l\u00e4sst: 214-mal holen wir im Schnitt jeden Tag unser Handy aus der Tasche und schauen auf das Display. In den meisten F\u00e4llen nicht, weil wir eine Nachricht erhalten haben oder im Internet etwas nachsehen wollen, sondern weil unser Gehirn uns den Befehl dazu gibt.<\/span><\/p>\n<h4><b>T\u00e4gliche Routine als Energiesparmodus f\u00fcr das Gehirn<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Das Gehirn gibt Millionen Menschen den Befehl, jeden Morgen einen <\/span><a href=\"https:\/\/www.weltderwunder.de\/artikel\/warum-macht-kaffee-munter\"><span style=\"font-weight: 400;\">Kaffee<\/span><\/a><span style=\"font-weight: 400;\"> zu trinken, nach dem Essen eine Zigarette zu rauchen, abends ein Glas Wein zu trinken und mehr. Und das, obwohl wir wissen, dass all das gesundheitssch\u00e4dlich ist. Wir nennen diese wiederkehrenden Verhaltensweisen schlechte Gewohnheiten \u2013 unser Gehirn liebt sie jedoch wie kaum etwas anderes.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Der Grund: Automatismen sparen Energie. Tats\u00e4chlich fanden Forscher heraus, dass die Areale, die f\u00fcr komplexe Denkprozesse und Entscheidungen verantwortlich sind, im Routine Modus ihren Dienst einstellen. Im Umkehrschluss bedeutet das: Wer seine Gewohnheiten \u00e4ndern will, steht vor einer der gr\u00f6\u00dften Herausforderungen \u00fcberhaupt:<\/span> <span style=\"font-weight: 400;\">Denn er muss sein Neuronennetzwerk und das gesamte Motivationssystem des Gehirns umprogrammieren.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201eZwischen 30 und 50 Prozent unseres t\u00e4glichen Handelns werden durch Gewohnheiten bestimmt\u201c, sagt Bas Verplanken, Professor f\u00fcr Sozialpsychologie an der University of Bath.<\/span><\/p>\n<h4><b>Warum f\u00e4llt es uns so schwer, schlechte Gewohnheiten aufzugeben?<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">20-mal die Stunde auf das Smartphone schauen, f\u00fcnf Tassen Kaffee am Tag, beim Fernsehen Fingern\u00e4gel kauen: Jeder Mensch entwickelt in seinem Leben schlechte Gewohnheiten. Der Hauptschuldige daf\u00fcr: unser selbsts\u00fcchtiges Gehirn. \u201eDie Konfrontation mit neuen und komplizierten Dingen erfordert Bewusstsein, Aufmerksamkeit und Konzentration \u2013 das Gehirn strebt darum danach, alles zu routinisieren\u201c, erkl\u00e4rt Gerhard Roth von der Universit\u00e4t Bremen.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Der Professor am Institut f\u00fcr Hirnforschung besch\u00e4ftigt sich seit Jahren mit der Frage, warum man sich so schwer dazu motivieren kann, schlechte Gewohnheiten aufzugeben. \u201eGewohnheiten sind sowohl biologisch als auch neuronal billig. Ver\u00e4nderungen von Strukturen und Funktionen im Bereich des F\u00fchlens, Denkens und Handelns sind stoffwechselphysiologisch dagegen aufwendig und teuer\u201c, schreibt er in seinem Buch \u201eCoaching, Beratung und Gehirn\u201c.<\/span><\/p>\n<h4><b>Schlechte Gewohnheiten loswerden<\/b><\/h4>\n<p><span style=\"font-weight: 400;\">Schlechte Gewohnheiten ablegen, gespeicherte Verhaltens Pfade verlassen \u2013 aus den Erkenntnissen der Neurobiologie wei\u00df man: Es dauert mindestens 21 Tage, bis die alten <\/span><a href=\"https:\/\/www.weltderwunder.de\/artikel\/was-laesst-mich-aufgeben-und-was-weitermachen\"><span style=\"font-weight: 400;\">Motivationsmuster<\/span><\/a><span style=\"font-weight: 400;\"> im Gehirn gel\u00f6scht sind. Also quasi das biochemische Update abgeschlossen und das alte Programm \u00fcberschrieben ist. Am effektivsten funktioniert dieser Prozess, wenn man sich an folgende drei Grundregeln h\u00e4lt:<br \/>\n<\/span><\/p>\n<p><b>1. Seien Sie auf Angriffe vorbereitet<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Die Psychologin Gabriele Oettingen stellte eine Erfolgsformel zur Selbstmotivation auf. Die Bezeichnung WOOP steht f\u00fcr \u201eWish-outcome-obstacle-plan\u201c. Das bedeutet: Wer seine schlechte Gewohnheit abstellen will, sollte auf Verlockungen, Hindernisse und Stolpersteine (obstacles) vorbereitet sein. So kann man sich bereits im Vorfeld einen Plan zurechtlegen, wie man auf die Gefahren reagiert.<\/span><\/p>\n<p><b>2. Wechseln Sie das Setting<\/b><\/p>\n<p><span style=\"font-weight: 400;\">\u201eGewohnheiten werden immer von Reizen aus der Umwelt angesto\u00dfen\u201c, sagt Bas Verplanken von der University of Bath. \u201eUnd um es noch schwieriger zu machen: Meist ist es nicht nur ein Reiz, sondern ein ganzer Kontext, in der die Gewohnheit eingebettet ist.\u201c Das bedeutet: Viele allt\u00e4gliche Handlungen wiederholen wir meist in einem ganz bestimmten Setting: an einem speziellen Ort, zu einer gewohnten Zeit, in gewissen Stimmungslagen oder mit ausgew\u00e4hlten Menschen. Genau dieses Setting sollte man wechseln. So fand die Psychologin Wendy Wood beispielsweise heraus, dass <\/span><a href=\"https:\/\/www.weltderwunder.de\/artikel\/10-tipps-mit-dem-rauchen-aufzuhoeren\"><span style=\"font-weight: 400;\">Raucher<\/span><\/a><span style=\"font-weight: 400;\">, die ihr Laster aufgeben wollten, doppelt so erfolgreich waren, wenn sie im Urlaub damit anfingen.<\/span><\/p>\n<p><b>3. Suchen Sie eine Ersatz-Routine<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Ein effektiver Weg f\u00fcr die Umprogrammierung ist es, ein neues Routineprogramm im Gehirn zu installieren. Also, eine schlechte Angewohnheit durch eine gute zu ersetzen. So kann man beispielsweise die Zigarette nach dem Essen durch einen Apfel ersetzen. Hat man es geschafft, einen neuen Anreiz im Motivationsmuster des Gehirns zu etablieren, wird die Gewohnheit buchst\u00e4blich zum Selbstl\u00e4ufer. So wie bei <\/span><a href=\"https:\/\/www.weltderwunder.de\/ironman-trotz-erschopfung-weiterlaufen\/\"><span style=\"font-weight: 400;\">Jan Frodeno<\/span><\/a><span style=\"font-weight: 400;\">, dessen Routine ihn fast schon unbewusst jeden Tag zum Sport gehen l\u00e4sst. Damit er, wenn es darauf ankommt, topmotiviert in den Wettkampf gehen \u2013 und seinen inneren Schweinehund \u00fcberwinden kann. Routine eben \u2026<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Manche schlechten Gewohnheiten m\u00f6chten wir am liebsten so schnell wie m\u00f6glich loswerden. Doch warum ist das oft so schwierig? Wieso h\u00e4ngt unser Gehirn so sehr an wiederkehrenden Verhaltensweisen und was k\u00f6nnen wir dagegen tun? Es ist eine Zahl, die selbst Psychologen aufhorchen l\u00e4sst: 214-mal holen wir im Schnitt jeden Tag unser Handy aus der Tasche [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1653,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[84,88,85,86,87,89],"class_list":["post-1652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mentale-gesundheit","tag-ersatz-routine","tag-gewohnheiten","tag-loswerden","tag-routine","tag-schlechte-gewohnheiten","tag-taegliche-routine"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/fit-up.com\/en\/wp-json\/wp\/v2\/posts\/1652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fit-up.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fit-up.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fit-up.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fit-up.com\/en\/wp-json\/wp\/v2\/comments?post=1652"}],"version-history":[{"count":1,"href":"https:\/\/fit-up.com\/en\/wp-json\/wp\/v2\/posts\/1652\/revisions"}],"predecessor-version":[{"id":1654,"href":"https:\/\/fit-up.com\/en\/wp-json\/wp\/v2\/posts\/1652\/revisions\/1654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fit-up.com\/en\/wp-json\/wp\/v2\/media\/1653"}],"wp:attachment":[{"href":"https:\/\/fit-up.com\/en\/wp-json\/wp\/v2\/media?parent=1652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fit-up.com\/en\/wp-json\/wp\/v2\/categories?post=1652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fit-up.com\/en\/wp-json\/wp\/v2\/tags?post=1652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}